{"id":18628,"date":"2025-10-22T08:41:21","date_gmt":"2025-10-22T06:41:21","guid":{"rendered":"https:\/\/warex-cz.mom\/?post_type=reference&#038;p=18628"},"modified":"2025-10-22T09:07:52","modified_gmt":"2025-10-22T07:07:52","slug":"realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade","status":"publish","type":"reference","link":"https:\/\/warex-cz.mom\/de\/referenz\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\/","title":{"rendered":"Realisierung eines B\u00fcrogeb\u00e4udes aus Wohnmodulen mit Sanit\u00e4ranlagen"},"content":{"rendered":"\n<p>Das Geb\u00e4ude umfasst voll ausgestattete Sanit\u00e4ranlagen \u2013 Toilette und Waschbecken -, die den Hygienestandards und Erwartungen der Mitarbeiter entsprechen. Alles ist in den Modulen integriert, ohne dass zus\u00e4tzliche bauliche Ver\u00e4nderungen erforderlich sind.<\/p>\n\n\n\n<p>Um ganzj\u00e4hrig ein optimales Raumklima zu gew\u00e4hrleisten, ist das Geb\u00e4ude mit einer Split-Klimaanlage ausgestattet. Dies erm\u00f6glicht eine individuelle Temperaturregelung in jedem Raum und tr\u00e4gt zu mehr Komfort und Produktivit\u00e4t der Mitarbeiter bei.<\/p>\n\n\n\n<p>In Bezug auf \u00c4sthetik und technische Gestaltung ist die Verwendung einer Kassettenfassade ein Hit. Sie verleiht dem Geb\u00e4ude nicht nur ein modernes Aussehen, sondern gew\u00e4hrleistet auch eine lange Lebensdauer, einfache Wartung und Schutz vor Witterungseinfl\u00fcssen. Dar\u00fcber hinaus erm\u00f6glicht die Kassettenfassade eine Harmonisierung mit der Corporate Identity oder der umgebenden Architektur.<\/p>\n\n\n\n<p>Die einzelnen Module wurden so zusammengesetzt, dass sie genau den betrieblichen Anforderungen des Kunden entsprechen \u2013 einschlie\u00dflich der Anordnung von B\u00fcros und Besprechungsr\u00e4umen.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"18051\" src=\"https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare.png\" alt=\"\" class=\"wp-image-18051\" srcset=\"https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare.png 1024w, https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare-300x300.png 300w, https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare-150x150.png 150w, https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare-768x768.png 768w, https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare-400x400.png 400w, https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare-600x600.png 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"18047\" src=\"https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare_interier-1024x577.jpg\" alt=\"\" class=\"wp-image-18047\" srcset=\"https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare_interier-1024x577.jpg 1024w, https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare_interier-300x169.jpg 300w, https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare_interier-768x432.jpg 768w, https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare_interier-1536x865.jpg 1536w, https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare_interier-2048x1153.jpg 2048w, https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare_interier-1320x743.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Das Geb\u00e4ude umfasst voll ausgestattete Sanit\u00e4ranlagen \u2013 Toilette und Waschbecken -, die den Hygienestandards und Erwartungen der Mitarbeiter entsprechen.<\/p>\n","protected":false},"featured_media":18051,"template":"","reference_category":[],"class_list":["post-18628","reference","type-reference","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Warex - Realisierung eines B\u00fcrogeb\u00e4udes aus Wohnmodulen<\/title>\n<meta name=\"description\" content=\"Das Geb\u00e4ude umfasst voll ausgestattete Sanit\u00e4ranlagen \u2013 Toilette und Waschbecken -, die den Hygienestandards und Erwartungen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/warex-cz.mom\/de\/referenz\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Warex - Realisierung eines B\u00fcrogeb\u00e4udes aus Wohnmodulen\" \/>\n<meta property=\"og:description\" content=\"Das Geb\u00e4ude umfasst voll ausgestattete Sanit\u00e4ranlagen \u2013 Toilette und Waschbecken -, die den Hygienestandards und Erwartungen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/warex-cz.mom\/de\/referenz\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\/\" \/>\n<meta property=\"og:site_name\" content=\"Warex\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WarexCzech\/notifications\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-22T07:07:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/referenz\\\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\\\/\",\"url\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/referenz\\\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\\\/\",\"name\":\"Warex - Realisierung eines B\u00fcrogeb\u00e4udes aus Wohnmodulen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/referenz\\\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/referenz\\\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/warex-cz.mom\\\/app\\\/uploads\\\/2025\\\/06\\\/kancelare.png\",\"datePublished\":\"2025-10-22T06:41:21+00:00\",\"dateModified\":\"2025-10-22T07:07:52+00:00\",\"description\":\"Das Geb\u00e4ude umfasst voll ausgestattete Sanit\u00e4ranlagen \u2013 Toilette und Waschbecken -, die den Hygienestandards und Erwartungen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/referenz\\\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/warex-cz.mom\\\/de\\\/referenz\\\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/referenz\\\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/warex-cz.mom\\\/app\\\/uploads\\\/2025\\\/06\\\/kancelare.png\",\"contentUrl\":\"https:\\\/\\\/warex-cz.mom\\\/app\\\/uploads\\\/2025\\\/06\\\/kancelare.png\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/referenz\\\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"References\",\"item\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/referenz\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Realisierung eines B\u00fcrogeb\u00e4udes aus Wohnmodulen mit Sanit\u00e4ranlagen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/\",\"name\":\"Warex\",\"description\":\"Web spole\u010dnosti Warex\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Warex - Realisierung eines B\u00fcrogeb\u00e4udes aus Wohnmodulen","description":"Das Geb\u00e4ude umfasst voll ausgestattete Sanit\u00e4ranlagen \u2013 Toilette und Waschbecken -, die den Hygienestandards und Erwartungen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/warex-cz.mom\/de\/referenz\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\/","og_locale":"de_DE","og_type":"article","og_title":"Warex - Realisierung eines B\u00fcrogeb\u00e4udes aus Wohnmodulen","og_description":"Das Geb\u00e4ude umfasst voll ausgestattete Sanit\u00e4ranlagen \u2013 Toilette und Waschbecken -, die den Hygienestandards und Erwartungen.","og_url":"https:\/\/warex-cz.mom\/de\/referenz\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\/","og_site_name":"Warex","article_publisher":"https:\/\/www.facebook.com\/WarexCzech\/notifications\/","article_modified_time":"2025-10-22T07:07:52+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/warex-cz.mom\/de\/referenz\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\/","url":"https:\/\/warex-cz.mom\/de\/referenz\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\/","name":"Warex - Realisierung eines B\u00fcrogeb\u00e4udes aus Wohnmodulen","isPartOf":{"@id":"https:\/\/warex-cz.mom\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/warex-cz.mom\/de\/referenz\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\/#primaryimage"},"image":{"@id":"https:\/\/warex-cz.mom\/de\/referenz\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\/#primaryimage"},"thumbnailUrl":"https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare.png","datePublished":"2025-10-22T06:41:21+00:00","dateModified":"2025-10-22T07:07:52+00:00","description":"Das Geb\u00e4ude umfasst voll ausgestattete Sanit\u00e4ranlagen \u2013 Toilette und Waschbecken -, die den Hygienestandards und Erwartungen.","breadcrumb":{"@id":"https:\/\/warex-cz.mom\/de\/referenz\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/warex-cz.mom\/de\/referenz\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/warex-cz.mom\/de\/referenz\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\/#primaryimage","url":"https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare.png","contentUrl":"https:\/\/warex-cz.mom\/app\/uploads\/2025\/06\/kancelare.png","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/warex-cz.mom\/de\/referenz\/realisierung-eines-buerogebaeudes-aus-wohnmodulen-mit-sanitaeranlagen-klimaanlage-und-eleganter-kassettenfassade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/warex-cz.mom\/de\/"},{"@type":"ListItem","position":2,"name":"References","item":"https:\/\/warex-cz.mom\/de\/referenz\/"},{"@type":"ListItem","position":3,"name":"Realisierung eines B\u00fcrogeb\u00e4udes aus Wohnmodulen mit Sanit\u00e4ranlagen"}]},{"@type":"WebSite","@id":"https:\/\/warex-cz.mom\/de\/#website","url":"https:\/\/warex-cz.mom\/de\/","name":"Warex","description":"Web spole\u010dnosti Warex","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/warex-cz.mom\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/reference\/18628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/media\/18051"}],"wp:attachment":[{"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/media?parent=18628"}],"wp:term":[{"taxonomy":"reference_category","embeddable":true,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/reference_category?post=18628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}