{"id":8705,"date":"2022-07-08T12:12:23","date_gmt":"2022-07-08T10:12:23","guid":{"rendered":"https:\/\/warex-cz.mom\/?p=8705"},"modified":"2022-07-08T12:12:29","modified_gmt":"2022-07-08T10:12:29","slug":"bauen-sie-ein-verwaltungsgebaeude","status":"publish","type":"post","link":"https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/","title":{"rendered":"Bauen Sie ein Verwaltungsgeb\u00e4ude\u00a0"},"content":{"rendered":"\n<p>Das Verwaltungsgeb\u00e4ude kann auch aus architektonischer Sicht so konzipiert werden, dass niemand dessen modularen Ursprung erraten w\u00fcrde. Auch ein gro\u00dfr\u00e4umiger Besprechungsraum oder ein Open Space k\u00f6nnen realisiert werden. Die Grenzen werden nur durch den Auftraggeber vorgegeben. Effizienz und Wirtschafltichkeit&nbsp;\u2013 das sind die eindeutigen Vorteile dieser Bauweise.<\/p>\n\n\n\n<p>Wir bieten jetzt die M\u00f6glichkeit, Standard-Wohnmodule mit einer Tiefstpreisgarantie zu erwerben. Weitere Informationen finden Sie hier.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"543\" src=\"https:\/\/warex-cz.mom\/app\/uploads\/2022\/07\/obytny_modul-1024x543.png\" alt=\"\" class=\"wp-image-8695\" srcset=\"https:\/\/warex-cz.mom\/app\/uploads\/2022\/07\/obytny_modul-1024x543.png 1024w, https:\/\/warex-cz.mom\/app\/uploads\/2022\/07\/obytny_modul-300x159.png 300w, https:\/\/warex-cz.mom\/app\/uploads\/2022\/07\/obytny_modul-768x407.png 768w, https:\/\/warex-cz.mom\/app\/uploads\/2022\/07\/obytny_modul-1536x814.png 1536w, https:\/\/warex-cz.mom\/app\/uploads\/2022\/07\/obytny_modul-2048x1086.png 2048w, https:\/\/warex-cz.mom\/app\/uploads\/2022\/07\/obytny_modul-1320x700.png 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Das Verwaltungsgeb\u00e4ude kann auch aus architektonischer Sicht so konzipiert werden, dass niemand dessen modularen Ursprung erraten w\u00fcrde. Auch ein gro\u00dfr\u00e4umiger Besprechungsraum oder ein Open Space k\u00f6nnen realisiert werden. Die Grenzen werden nur durch den Auftraggeber vorgegeben. Effizienz und Wirtschafltichkeit&nbsp;\u2013 das sind die eindeutigen Vorteile dieser Bauweise. Wir bieten jetzt die M\u00f6glichkeit, Standard-Wohnmodule mit einer Tiefstpreisgarantie &hellip; <a href=\"https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/\">Continued<\/a><\/p>\n","protected":false},"author":13,"featured_media":8702,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[38],"tags":[],"class_list":["post-8705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hintergrund-nachrichten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Warex - Aktuality<\/title>\n<meta name=\"description\" content=\"as Verwaltungsgeb\u00e4ude kann auch aus architektonischer Sicht so konzipiert werden, dass niemand dessen modularen Ursprung erraten w\u00fcrde.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Warex - Aktuality\" \/>\n<meta property=\"og:description\" content=\"as Verwaltungsgeb\u00e4ude kann auch aus architektonischer Sicht so konzipiert werden, dass niemand dessen modularen Ursprung erraten w\u00fcrde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/\" \/>\n<meta property=\"og:site_name\" content=\"Warex\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WarexCzech\/notifications\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-08T10:12:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-08T10:12:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/warex-cz.mom\/app\/uploads\/2022\/07\/obytny_kontejner-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2363\" \/>\n\t<meta property=\"og:image:height\" content=\"1773\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Miloslav Ju\u0159en\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miloslav Ju\u0159en\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/aktuality\\\/hintergrund-nachrichten\\\/bauen-sie-ein-verwaltungsgebaeude\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/aktuality\\\/hintergrund-nachrichten\\\/bauen-sie-ein-verwaltungsgebaeude\\\/\"},\"author\":{\"name\":\"Miloslav Ju\u0159en\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/#\\\/schema\\\/person\\\/9826157e7431ae05b463018d35a9b5ea\"},\"headline\":\"Bauen Sie ein Verwaltungsgeb\u00e4ude\u00a0\",\"datePublished\":\"2022-07-08T10:12:23+00:00\",\"dateModified\":\"2022-07-08T10:12:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/aktuality\\\/hintergrund-nachrichten\\\/bauen-sie-ein-verwaltungsgebaeude\\\/\"},\"wordCount\":74,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/aktuality\\\/hintergrund-nachrichten\\\/bauen-sie-ein-verwaltungsgebaeude\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/warex-cz.mom\\\/app\\\/uploads\\\/2022\\\/07\\\/obytny_kontejner-1.png\",\"articleSection\":[\"HINTERGRUND-NACHRICHTEN\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/warex-cz.mom\\\/de\\\/aktuality\\\/hintergrund-nachrichten\\\/bauen-sie-ein-verwaltungsgebaeude\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/aktuality\\\/hintergrund-nachrichten\\\/bauen-sie-ein-verwaltungsgebaeude\\\/\",\"url\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/aktuality\\\/hintergrund-nachrichten\\\/bauen-sie-ein-verwaltungsgebaeude\\\/\",\"name\":\"Warex - Aktuality\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/aktuality\\\/hintergrund-nachrichten\\\/bauen-sie-ein-verwaltungsgebaeude\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/aktuality\\\/hintergrund-nachrichten\\\/bauen-sie-ein-verwaltungsgebaeude\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/warex-cz.mom\\\/app\\\/uploads\\\/2022\\\/07\\\/obytny_kontejner-1.png\",\"datePublished\":\"2022-07-08T10:12:23+00:00\",\"dateModified\":\"2022-07-08T10:12:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/#\\\/schema\\\/person\\\/9826157e7431ae05b463018d35a9b5ea\"},\"description\":\"as Verwaltungsgeb\u00e4ude kann auch aus architektonischer Sicht so konzipiert werden, dass niemand dessen modularen Ursprung erraten w\u00fcrde.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/aktuality\\\/hintergrund-nachrichten\\\/bauen-sie-ein-verwaltungsgebaeude\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/warex-cz.mom\\\/de\\\/aktuality\\\/hintergrund-nachrichten\\\/bauen-sie-ein-verwaltungsgebaeude\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/aktuality\\\/hintergrund-nachrichten\\\/bauen-sie-ein-verwaltungsgebaeude\\\/#primaryimage\",\"url\":\"https:\\\/\\\/warex-cz.mom\\\/app\\\/uploads\\\/2022\\\/07\\\/obytny_kontejner-1.png\",\"contentUrl\":\"https:\\\/\\\/warex-cz.mom\\\/app\\\/uploads\\\/2022\\\/07\\\/obytny_kontejner-1.png\",\"width\":2363,\"height\":1773},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/aktuality\\\/hintergrund-nachrichten\\\/bauen-sie-ein-verwaltungsgebaeude\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bauen Sie ein Verwaltungsgeb\u00e4ude\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/\",\"name\":\"Warex\",\"description\":\"Web spole\u010dnosti Warex\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/#\\\/schema\\\/person\\\/9826157e7431ae05b463018d35a9b5ea\",\"name\":\"Miloslav Ju\u0159en\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d35f44e2eaeab2aad2e7d8c71c9e96a478e2aa11b67e10d48b562fe03f4fbc0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d35f44e2eaeab2aad2e7d8c71c9e96a478e2aa11b67e10d48b562fe03f4fbc0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d35f44e2eaeab2aad2e7d8c71c9e96a478e2aa11b67e10d48b562fe03f4fbc0?s=96&d=mm&r=g\",\"caption\":\"Miloslav Ju\u0159en\"},\"sameAs\":[\"https:\\\/\\\/warex-cz.mom\\\/\"],\"url\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/aktuality\\\/author\\\/miloslav\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Warex - Aktuality","description":"as Verwaltungsgeb\u00e4ude kann auch aus architektonischer Sicht so konzipiert werden, dass niemand dessen modularen Ursprung erraten w\u00fcrde.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/","og_locale":"de_DE","og_type":"article","og_title":"Warex - Aktuality","og_description":"as Verwaltungsgeb\u00e4ude kann auch aus architektonischer Sicht so konzipiert werden, dass niemand dessen modularen Ursprung erraten w\u00fcrde.","og_url":"https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/","og_site_name":"Warex","article_publisher":"https:\/\/www.facebook.com\/WarexCzech\/notifications\/","article_published_time":"2022-07-08T10:12:23+00:00","article_modified_time":"2022-07-08T10:12:29+00:00","og_image":[{"width":2363,"height":1773,"url":"https:\/\/warex-cz.mom\/app\/uploads\/2022\/07\/obytny_kontejner-1.png","type":"image\/png"}],"author":"Miloslav Ju\u0159en","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Miloslav Ju\u0159en","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/#article","isPartOf":{"@id":"https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/"},"author":{"name":"Miloslav Ju\u0159en","@id":"https:\/\/warex-cz.mom\/de\/#\/schema\/person\/9826157e7431ae05b463018d35a9b5ea"},"headline":"Bauen Sie ein Verwaltungsgeb\u00e4ude\u00a0","datePublished":"2022-07-08T10:12:23+00:00","dateModified":"2022-07-08T10:12:29+00:00","mainEntityOfPage":{"@id":"https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/"},"wordCount":74,"commentCount":0,"image":{"@id":"https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/#primaryimage"},"thumbnailUrl":"https:\/\/warex-cz.mom\/app\/uploads\/2022\/07\/obytny_kontejner-1.png","articleSection":["HINTERGRUND-NACHRICHTEN"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/","url":"https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/","name":"Warex - Aktuality","isPartOf":{"@id":"https:\/\/warex-cz.mom\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/#primaryimage"},"image":{"@id":"https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/#primaryimage"},"thumbnailUrl":"https:\/\/warex-cz.mom\/app\/uploads\/2022\/07\/obytny_kontejner-1.png","datePublished":"2022-07-08T10:12:23+00:00","dateModified":"2022-07-08T10:12:29+00:00","author":{"@id":"https:\/\/warex-cz.mom\/de\/#\/schema\/person\/9826157e7431ae05b463018d35a9b5ea"},"description":"as Verwaltungsgeb\u00e4ude kann auch aus architektonischer Sicht so konzipiert werden, dass niemand dessen modularen Ursprung erraten w\u00fcrde.","breadcrumb":{"@id":"https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/#primaryimage","url":"https:\/\/warex-cz.mom\/app\/uploads\/2022\/07\/obytny_kontejner-1.png","contentUrl":"https:\/\/warex-cz.mom\/app\/uploads\/2022\/07\/obytny_kontejner-1.png","width":2363,"height":1773},{"@type":"BreadcrumbList","@id":"https:\/\/warex-cz.mom\/de\/aktuality\/hintergrund-nachrichten\/bauen-sie-ein-verwaltungsgebaeude\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/warex-cz.mom\/de\/"},{"@type":"ListItem","position":2,"name":"Bauen Sie ein Verwaltungsgeb\u00e4ude\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/warex-cz.mom\/de\/#website","url":"https:\/\/warex-cz.mom\/de\/","name":"Warex","description":"Web spole\u010dnosti Warex","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/warex-cz.mom\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/warex-cz.mom\/de\/#\/schema\/person\/9826157e7431ae05b463018d35a9b5ea","name":"Miloslav Ju\u0159en","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/3d35f44e2eaeab2aad2e7d8c71c9e96a478e2aa11b67e10d48b562fe03f4fbc0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3d35f44e2eaeab2aad2e7d8c71c9e96a478e2aa11b67e10d48b562fe03f4fbc0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3d35f44e2eaeab2aad2e7d8c71c9e96a478e2aa11b67e10d48b562fe03f4fbc0?s=96&d=mm&r=g","caption":"Miloslav Ju\u0159en"},"sameAs":["https:\/\/warex-cz.mom\/"],"url":"https:\/\/warex-cz.mom\/de\/aktuality\/author\/miloslav\/"}]}},"_links":{"self":[{"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/posts\/8705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/comments?post=8705"}],"version-history":[{"count":1,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/posts\/8705\/revisions"}],"predecessor-version":[{"id":8706,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/posts\/8705\/revisions\/8706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/media\/8702"}],"wp:attachment":[{"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/media?parent=8705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/categories?post=8705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/tags?post=8705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}