{"id":900,"date":"2020-02-11T15:22:47","date_gmt":"2020-02-11T15:22:47","guid":{"rendered":"https:\/\/warex-cz.mom\/vymenitelne-nastavby\/"},"modified":"2026-01-12T20:47:40","modified_gmt":"2026-01-12T19:47:40","slug":"wechselaufbauten","status":"publish","type":"page","link":"https:\/\/warex-cz.mom\/de\/wechselaufbauten\/","title":{"rendered":"Wechselaufbauten"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":503,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"views\/template-exchangable-addons.blade.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-900","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Warex - Wechselaufbauten<\/title>\n<meta name=\"description\" content=\"Wechselbeh\u00e4lter (WB), Wechselbr\u00fccke, Wechselpritsche, Wechselaufbaubr\u00fccke (WAB), Wechselkoffer, Wechselladebeh\u00e4lter (WELAB) geh\u00f6ren zur Gruppe der intermodalen Ladeeinheiten (UTI), die f\u00fcr den europ\u00e4ischen kombinierten Verkehr auf Stra\u00dfe, Schiene, der Binnenschiff- und Seefahrt geeignet sind.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/warex-cz.mom\/de\/wechselaufbauten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Warex - Wechselaufbauten\" \/>\n<meta property=\"og:description\" content=\"Wechselbeh\u00e4lter (WB), Wechselbr\u00fccke, Wechselpritsche, Wechselaufbaubr\u00fccke (WAB), Wechselkoffer, Wechselladebeh\u00e4lter (WELAB) geh\u00f6ren zur Gruppe der intermodalen Ladeeinheiten (UTI), die f\u00fcr den europ\u00e4ischen kombinierten Verkehr auf Stra\u00dfe, Schiene, der Binnenschiff- und Seefahrt geeignet sind.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/warex-cz.mom\/de\/wechselaufbauten\/\" \/>\n<meta property=\"og:site_name\" content=\"Warex\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WarexCzech\/notifications\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-12T19:47:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/warex-cz.mom\/app\/uploads\/2020\/02\/DSC00629.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"643\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/wechselaufbauten\\\/\",\"url\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/wechselaufbauten\\\/\",\"name\":\"Warex - Wechselaufbauten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/wechselaufbauten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/wechselaufbauten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/warex-cz.mom\\\/app\\\/uploads\\\/2020\\\/02\\\/DSC00629.jpg\",\"datePublished\":\"2020-02-11T15:22:47+00:00\",\"dateModified\":\"2026-01-12T19:47:40+00:00\",\"description\":\"Wechselbeh\u00e4lter (WB), Wechselbr\u00fccke, Wechselpritsche, Wechselaufbaubr\u00fccke (WAB), Wechselkoffer, Wechselladebeh\u00e4lter (WELAB) geh\u00f6ren zur Gruppe der intermodalen Ladeeinheiten (UTI), die f\u00fcr den europ\u00e4ischen kombinierten Verkehr auf Stra\u00dfe, Schiene, der Binnenschiff- und Seefahrt geeignet sind.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/wechselaufbauten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/warex-cz.mom\\\/de\\\/wechselaufbauten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/wechselaufbauten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/warex-cz.mom\\\/app\\\/uploads\\\/2020\\\/02\\\/DSC00629.jpg\",\"contentUrl\":\"https:\\\/\\\/warex-cz.mom\\\/app\\\/uploads\\\/2020\\\/02\\\/DSC00629.jpg\",\"width\":960,\"height\":643,\"caption\":\"Warex - Wechselaufbauten\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/wechselaufbauten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wechselaufbauten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/\",\"name\":\"Warex\",\"description\":\"Web spole\u010dnosti Warex\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Warex - Wechselaufbauten","description":"Wechselbeh\u00e4lter (WB), Wechselbr\u00fccke, Wechselpritsche, Wechselaufbaubr\u00fccke (WAB), Wechselkoffer, Wechselladebeh\u00e4lter (WELAB) geh\u00f6ren zur Gruppe der intermodalen Ladeeinheiten (UTI), die f\u00fcr den europ\u00e4ischen kombinierten Verkehr auf Stra\u00dfe, Schiene, der Binnenschiff- und Seefahrt geeignet sind.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/warex-cz.mom\/de\/wechselaufbauten\/","og_locale":"de_DE","og_type":"article","og_title":"Warex - Wechselaufbauten","og_description":"Wechselbeh\u00e4lter (WB), Wechselbr\u00fccke, Wechselpritsche, Wechselaufbaubr\u00fccke (WAB), Wechselkoffer, Wechselladebeh\u00e4lter (WELAB) geh\u00f6ren zur Gruppe der intermodalen Ladeeinheiten (UTI), die f\u00fcr den europ\u00e4ischen kombinierten Verkehr auf Stra\u00dfe, Schiene, der Binnenschiff- und Seefahrt geeignet sind.","og_url":"https:\/\/warex-cz.mom\/de\/wechselaufbauten\/","og_site_name":"Warex","article_publisher":"https:\/\/www.facebook.com\/WarexCzech\/notifications\/","article_modified_time":"2026-01-12T19:47:40+00:00","og_image":[{"width":960,"height":643,"url":"https:\/\/warex-cz.mom\/app\/uploads\/2020\/02\/DSC00629.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/warex-cz.mom\/de\/wechselaufbauten\/","url":"https:\/\/warex-cz.mom\/de\/wechselaufbauten\/","name":"Warex - Wechselaufbauten","isPartOf":{"@id":"https:\/\/warex-cz.mom\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/warex-cz.mom\/de\/wechselaufbauten\/#primaryimage"},"image":{"@id":"https:\/\/warex-cz.mom\/de\/wechselaufbauten\/#primaryimage"},"thumbnailUrl":"https:\/\/warex-cz.mom\/app\/uploads\/2020\/02\/DSC00629.jpg","datePublished":"2020-02-11T15:22:47+00:00","dateModified":"2026-01-12T19:47:40+00:00","description":"Wechselbeh\u00e4lter (WB), Wechselbr\u00fccke, Wechselpritsche, Wechselaufbaubr\u00fccke (WAB), Wechselkoffer, Wechselladebeh\u00e4lter (WELAB) geh\u00f6ren zur Gruppe der intermodalen Ladeeinheiten (UTI), die f\u00fcr den europ\u00e4ischen kombinierten Verkehr auf Stra\u00dfe, Schiene, der Binnenschiff- und Seefahrt geeignet sind.","breadcrumb":{"@id":"https:\/\/warex-cz.mom\/de\/wechselaufbauten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/warex-cz.mom\/de\/wechselaufbauten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/warex-cz.mom\/de\/wechselaufbauten\/#primaryimage","url":"https:\/\/warex-cz.mom\/app\/uploads\/2020\/02\/DSC00629.jpg","contentUrl":"https:\/\/warex-cz.mom\/app\/uploads\/2020\/02\/DSC00629.jpg","width":960,"height":643,"caption":"Warex - Wechselaufbauten"},{"@type":"BreadcrumbList","@id":"https:\/\/warex-cz.mom\/de\/wechselaufbauten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/warex-cz.mom\/de\/"},{"@type":"ListItem","position":2,"name":"Wechselaufbauten"}]},{"@type":"WebSite","@id":"https:\/\/warex-cz.mom\/de\/#website","url":"https:\/\/warex-cz.mom\/de\/","name":"Warex","description":"Web spole\u010dnosti Warex","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/warex-cz.mom\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/pages\/900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/comments?post=900"}],"version-history":[{"count":66,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/pages\/900\/revisions"}],"predecessor-version":[{"id":18907,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/pages\/900\/revisions\/18907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/media\/503"}],"wp:attachment":[{"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/media?parent=900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}