{"id":1069,"date":"2020-02-11T15:20:21","date_gmt":"2020-02-11T15:20:21","guid":{"rendered":"https:\/\/warex-cz.mom\/kontakt\/"},"modified":"2026-06-01T14:45:47","modified_gmt":"2026-06-01T12:45:47","slug":"kontakte","status":"publish","type":"page","link":"https:\/\/warex-cz.mom\/de\/kontakte\/","title":{"rendered":"Kontakte"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"views\/template-contact.blade.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1069","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Warex - Kontakte von Mitarbeitern des Unternehmens<\/title>\n<meta name=\"description\" content=\"Kontakte zu Warex-Mitarbeitern, die modulare Geb\u00e4ude, Stahlkonstruktionen, Tauschk\u00f6rper und die Vermietung von Containercontainern herstellen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/warex-cz.mom\/de\/kontakte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Warex - Kontakte von Mitarbeitern des Unternehmens\" \/>\n<meta property=\"og:description\" content=\"Kontakte zu Warex-Mitarbeitern, die modulare Geb\u00e4ude, Stahlkonstruktionen, Tauschk\u00f6rper und die Vermietung von Containercontainern herstellen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/warex-cz.mom\/de\/kontakte\/\" \/>\n<meta property=\"og:site_name\" content=\"Warex\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WarexCzech\/notifications\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T12:45:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/kontakte\\\/\",\"url\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/kontakte\\\/\",\"name\":\"Warex - Kontakte von Mitarbeitern des Unternehmens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/#website\"},\"datePublished\":\"2020-02-11T15:20:21+00:00\",\"dateModified\":\"2026-06-01T12:45:47+00:00\",\"description\":\"Kontakte zu Warex-Mitarbeitern, die modulare Geb\u00e4ude, Stahlkonstruktionen, Tauschk\u00f6rper und die Vermietung von Containercontainern herstellen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/kontakte\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/warex-cz.mom\\\/de\\\/kontakte\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/kontakte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kontakte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/\",\"name\":\"Warex\",\"description\":\"Web spole\u010dnosti Warex\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/warex-cz.mom\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Warex - Kontakte von Mitarbeitern des Unternehmens","description":"Kontakte zu Warex-Mitarbeitern, die modulare Geb\u00e4ude, Stahlkonstruktionen, Tauschk\u00f6rper und die Vermietung von Containercontainern herstellen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/warex-cz.mom\/de\/kontakte\/","og_locale":"de_DE","og_type":"article","og_title":"Warex - Kontakte von Mitarbeitern des Unternehmens","og_description":"Kontakte zu Warex-Mitarbeitern, die modulare Geb\u00e4ude, Stahlkonstruktionen, Tauschk\u00f6rper und die Vermietung von Containercontainern herstellen.","og_url":"https:\/\/warex-cz.mom\/de\/kontakte\/","og_site_name":"Warex","article_publisher":"https:\/\/www.facebook.com\/WarexCzech\/notifications\/","article_modified_time":"2026-06-01T12:45:47+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/warex-cz.mom\/de\/kontakte\/","url":"https:\/\/warex-cz.mom\/de\/kontakte\/","name":"Warex - Kontakte von Mitarbeitern des Unternehmens","isPartOf":{"@id":"https:\/\/warex-cz.mom\/de\/#website"},"datePublished":"2020-02-11T15:20:21+00:00","dateModified":"2026-06-01T12:45:47+00:00","description":"Kontakte zu Warex-Mitarbeitern, die modulare Geb\u00e4ude, Stahlkonstruktionen, Tauschk\u00f6rper und die Vermietung von Containercontainern herstellen.","breadcrumb":{"@id":"https:\/\/warex-cz.mom\/de\/kontakte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/warex-cz.mom\/de\/kontakte\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/warex-cz.mom\/de\/kontakte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/warex-cz.mom\/de\/"},{"@type":"ListItem","position":2,"name":"Kontakte"}]},{"@type":"WebSite","@id":"https:\/\/warex-cz.mom\/de\/#website","url":"https:\/\/warex-cz.mom\/de\/","name":"Warex","description":"Web spole\u010dnosti Warex","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/warex-cz.mom\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/pages\/1069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/comments?post=1069"}],"version-history":[{"count":133,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/pages\/1069\/revisions"}],"predecessor-version":[{"id":19676,"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/pages\/1069\/revisions\/19676"}],"wp:attachment":[{"href":"https:\/\/warex-cz.mom\/de\/wp-json\/wp\/v2\/media?parent=1069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}